{"id":197,"count":1,"description":"","link":"https:\/\/onestopultra.co.uk\/index.php\/tag\/24-hours\/","name":"24 hours","slug":"24-hours","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/onestopultra.co.uk\/index.php\/wp-json\/wp\/v2\/tags\/197"}],"collection":[{"href":"https:\/\/onestopultra.co.uk\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/onestopultra.co.uk\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/onestopultra.co.uk\/index.php\/wp-json\/wp\/v2\/posts?tags=197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}